{"id":4472,"date":"2021-08-29T19:17:44","date_gmt":"2021-08-29T17:17:44","guid":{"rendered":"https:\/\/sites.dsu.univr.it\/tiresia\/?post_type=pubblication&#038;p=4472"},"modified":"2021-10-04T21:22:32","modified_gmt":"2021-10-04T19:22:32","slug":"silvia-lippi-trasgressioni-bataille-lacan","status":"publish","type":"pubblication","link":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/","title":{"rendered":"Silvia Lippi, Trasgressioni. Bataille, Lacan"},"content":{"rendered":"<p><span class=\"wpsdc-drop-cap\">L<\/span>a trasgressione consente l\u2019accesso al godimento. Ma fino a che punto? Fin dove \u00e8 possibile godere? Potremmo dire che ogni godimento \u00e8 innanzitutto godimento mortifero? Qualsiasi trasgressione sarebbe cio\u00e8 dannosa al punto da rivelare che occorre mettere a repentaglio la propria vita per poter godere?<\/p>\n<p>La trasgressione rimanda all\u2019infrazione, al disordine, alla libert\u00e0. Ma, paradossalmente, questa libert\u00e0 \u00e8 subordinata alla legge. La trasgressione \u00e8 una possibilit\u00e0 offerta dalla legge stessa, nient\u2019affatto la sua negazione. La legge continua ad esistere anche se non viene rispettata, non si annulla nel movimento che implica la sua trasgressione. \u00c8 nel rapporto, rischioso e aporetico, fra trasgressione e legge, vale a dire fra trasgressione e castrazione, che il soggetto lotta per uno spazio di godimento possibile.<\/p>\n<p>La trasgressione attraversa i concetti fondamentali della psicoanalisi: inconscio, desiderio, fantasma, godimento, pulsione, sintomo, struttura, parola. L\u2019autrice ne esplora le differenti sfaccettature alla luce degli apporti di Bataille e Lacan, sottolineando i punti di convergenza e divergenza del pensiero di questi due autori.<\/p>\n","protected":false},"featured_media":4473,"template":"","categorie_pubblicazioni":[27],"class_list":["post-4472","pubblication","type-pubblication","status-publish","has-post-thumbnail","hentry","categorie_pubblicazioni-collana-psy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Silvia Lippi, Trasgressioni. Bataille, Lacan - Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Silvia Lippi, Trasgressioni. Bataille, Lacan - Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi\" \/>\n<meta property=\"og:description\" content=\"La trasgressione consente l\u2019accesso al godimento. Ma fino a che punto? Fin dove \u00e8 possibile godere? Potremmo dire che ogni godimento \u00e8 innanzitutto godimento mortifero? Qualsiasi trasgressione sarebbe cio\u00e8 dannosa al punto da rivelare che occorre mettere a repentaglio la propria vita per poter godere? La trasgressione rimanda all\u2019infrazione, al disordine, alla libert\u00e0. Ma, paradossalmente,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/\" \/>\n<meta property=\"og:site_name\" content=\"Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-04T19:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"416\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/\",\"url\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/\",\"name\":\"Silvia Lippi, Trasgressioni. Bataille, Lacan - Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi\",\"isPartOf\":{\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp\",\"datePublished\":\"2021-08-29T17:17:44+00:00\",\"dateModified\":\"2021-10-04T19:22:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#primaryimage\",\"url\":\"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp\",\"contentUrl\":\"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp\",\"width\":416,\"height\":602},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sites.dsu.univr.it\/tiresia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Silvia Lippi, Trasgressioni. Bataille, Lacan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sites.dsu.univr.it\/tiresia\/#website\",\"url\":\"https:\/\/sites.dsu.univr.it\/tiresia\/\",\"name\":\"Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sites.dsu.univr.it\/tiresia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Silvia Lippi, Trasgressioni. Bataille, Lacan - Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/","og_locale":"it_IT","og_type":"article","og_title":"Silvia Lippi, Trasgressioni. Bataille, Lacan - Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi","og_description":"La trasgressione consente l\u2019accesso al godimento. Ma fino a che punto? Fin dove \u00e8 possibile godere? Potremmo dire che ogni godimento \u00e8 innanzitutto godimento mortifero? Qualsiasi trasgressione sarebbe cio\u00e8 dannosa al punto da rivelare che occorre mettere a repentaglio la propria vita per poter godere? La trasgressione rimanda all\u2019infrazione, al disordine, alla libert\u00e0. Ma, paradossalmente,...","og_url":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/","og_site_name":"Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi","article_modified_time":"2021-10-04T19:22:32+00:00","og_image":[{"width":416,"height":602,"url":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/","url":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/","name":"Silvia Lippi, Trasgressioni. Bataille, Lacan - Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi","isPartOf":{"@id":"https:\/\/sites.dsu.univr.it\/tiresia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#primaryimage"},"image":{"@id":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#primaryimage"},"thumbnailUrl":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp","datePublished":"2021-08-29T17:17:44+00:00","dateModified":"2021-10-04T19:22:32+00:00","breadcrumb":{"@id":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#primaryimage","url":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp","contentUrl":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-content\/uploads\/2021\/08\/Lippi.webp","width":416,"height":602},{"@type":"BreadcrumbList","@id":"https:\/\/sites.dsu.univr.it\/tiresia\/pubblication\/silvia-lippi-trasgressioni-bataille-lacan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.dsu.univr.it\/tiresia\/"},{"@type":"ListItem","position":2,"name":"Silvia Lippi, Trasgressioni. Bataille, Lacan"}]},{"@type":"WebSite","@id":"https:\/\/sites.dsu.univr.it\/tiresia\/#website","url":"https:\/\/sites.dsu.univr.it\/tiresia\/","name":"Tiresia \u2013 Centro di ricerca per la filosofia e la psicoanalisi","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.dsu.univr.it\/tiresia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-json\/wp\/v2\/pubblication\/4472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-json\/wp\/v2\/pubblication"}],"about":[{"href":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-json\/wp\/v2\/types\/pubblication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-json\/wp\/v2\/media\/4473"}],"wp:attachment":[{"href":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-json\/wp\/v2\/media?parent=4472"}],"wp:term":[{"taxonomy":"categorie_pubblicazioni","embeddable":true,"href":"https:\/\/sites.dsu.univr.it\/tiresia\/wp-json\/wp\/v2\/categorie_pubblicazioni?post=4472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}